{"id":45428,"date":"2023-12-16T12:40:05","date_gmt":"2023-12-16T09:40:05","guid":{"rendered":"https:\/\/fordcargoparca.com\/urunler\/fy-68755-01-02-nt110638catalli-flans-3227\/"},"modified":"2023-12-16T12:40:05","modified_gmt":"2023-12-16T09:40:05","slug":"fy-68755-01-02-nt110638catalli-flans-3227","status":"publish","type":"product","link":"https:\/\/fordcargoparca.com\/en\/urunler\/fy-68755-01-02-nt110638catalli-flans-3227\/","title":{"rendered":"FY 68755 01.02 N;T110638;CATALLI FLANS  (3227);;;;;"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":[],"product_cat":[15],"product_tag":[],"class_list":{"0":"post-45428","1":"product","2":"type-product","3":"status-publish","5":"product_cat-ford-cargo-yedek-parca","6":"badges-style-3","8":"first","9":"instock","10":"shipping-taxable","11":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>FY 68755 01.02 N;T110638;CATALLI FLANS (3227);;;;; - Kamil Y\u0131lmaz Otomotiv - Ford Cargo Yedek Par&ccedil;a<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fordcargoparca.com\/en\/urunler\/fy-68755-01-02-nt110638catalli-flans-3227\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FY 68755 01.02 N;T110638;CATALLI FLANS (3227);;;;; - Kamil Y\u0131lmaz Otomotiv - Ford Cargo Yedek Par&ccedil;a\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fordcargoparca.com\/en\/urunler\/fy-68755-01-02-nt110638catalli-flans-3227\/\" \/>\n<meta property=\"og:site_name\" content=\"Kamil Y\u0131lmaz Otomotiv - Ford Cargo Yedek Par&ccedil;a\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fordtrucksparts\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/fordcargoparca.com\/urunler\/fy-68755-01-02-nt110638catalli-flans-3227\/\",\"url\":\"https:\/\/fordcargoparca.com\/urunler\/fy-68755-01-02-nt110638catalli-flans-3227\/\",\"name\":\"FY 68755 01.02 N;T110638;CATALLI FLANS (3227);;;;; - Kamil Y\u0131lmaz Otomotiv - Ford Cargo Yedek Par&ccedil;a\",\"isPartOf\":{\"@id\":\"https:\/\/fordcargoparca.com\/#website\"},\"datePublished\":\"2023-12-16T09:40:05+00:00\",\"dateModified\":\"2023-12-16T09:40:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/fordcargoparca.com\/urunler\/fy-68755-01-02-nt110638catalli-flans-3227\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/fordcargoparca.com\/urunler\/fy-68755-01-02-nt110638catalli-flans-3227\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/fordcargoparca.com\/urunler\/fy-68755-01-02-nt110638catalli-flans-3227\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Anasayfa\",\"item\":\"https:\/\/fordcargoparca.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00dcr\u00fcnler\",\"item\":\"https:\/\/fordcargoparca.com\/urunler\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"FY 68755 01.02 N;T110638;CATALLI FLANS (3227);;;;;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/fordcargoparca.com\/#website\",\"url\":\"https:\/\/fordcargoparca.com\/\",\"name\":\"Kamil Y\u0131lmaz Otomotiv - Ford Cargo Par\u00e7a\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/fordcargoparca.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/fordcargoparca.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/fordcargoparca.com\/#organization\",\"name\":\"Kamil Y\u0131lmaz Otomotiv - Ford Cargo Par\u00e7a\",\"url\":\"https:\/\/fordcargoparca.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/fordcargoparca.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/fordcargoparca.com\/wp-content\/uploads\/2023\/07\/cropped-kamilyilmazlogo3.png\",\"contentUrl\":\"https:\/\/fordcargoparca.com\/wp-content\/uploads\/2023\/07\/cropped-kamilyilmazlogo3.png\",\"width\":1080,\"height\":720,\"caption\":\"Kamil Y\u0131lmaz Otomotiv - Ford Cargo Par\u00e7a\"},\"image\":{\"@id\":\"https:\/\/fordcargoparca.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/fordtrucksparts\/\",\"https:\/\/www.instagram.com\/kamilyilmazotomotiv\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FY 68755 01.02 N;T110638;CATALLI FLANS (3227);;;;; - Kamil Y\u0131lmaz Otomotiv - Ford Cargo Yedek Par&ccedil;a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fordcargoparca.com\/en\/urunler\/fy-68755-01-02-nt110638catalli-flans-3227\/","og_locale":"en_US","og_type":"article","og_title":"FY 68755 01.02 N;T110638;CATALLI FLANS (3227);;;;; - Kamil Y\u0131lmaz Otomotiv - Ford Cargo Yedek Par&ccedil;a","og_url":"https:\/\/fordcargoparca.com\/en\/urunler\/fy-68755-01-02-nt110638catalli-flans-3227\/","og_site_name":"Kamil Y\u0131lmaz Otomotiv - Ford Cargo Yedek Par&ccedil;a","article_publisher":"https:\/\/www.facebook.com\/fordtrucksparts\/","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fordcargoparca.com\/urunler\/fy-68755-01-02-nt110638catalli-flans-3227\/","url":"https:\/\/fordcargoparca.com\/urunler\/fy-68755-01-02-nt110638catalli-flans-3227\/","name":"FY 68755 01.02 N;T110638;CATALLI FLANS (3227);;;;; - Kamil Y\u0131lmaz Otomotiv - Ford Cargo Yedek Par&ccedil;a","isPartOf":{"@id":"https:\/\/fordcargoparca.com\/#website"},"datePublished":"2023-12-16T09:40:05+00:00","dateModified":"2023-12-16T09:40:05+00:00","breadcrumb":{"@id":"https:\/\/fordcargoparca.com\/urunler\/fy-68755-01-02-nt110638catalli-flans-3227\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fordcargoparca.com\/urunler\/fy-68755-01-02-nt110638catalli-flans-3227\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fordcargoparca.com\/urunler\/fy-68755-01-02-nt110638catalli-flans-3227\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Anasayfa","item":"https:\/\/fordcargoparca.com\/"},{"@type":"ListItem","position":2,"name":"\u00dcr\u00fcnler","item":"https:\/\/fordcargoparca.com\/urunler\/"},{"@type":"ListItem","position":3,"name":"FY 68755 01.02 N;T110638;CATALLI FLANS (3227);;;;;"}]},{"@type":"WebSite","@id":"https:\/\/fordcargoparca.com\/#website","url":"https:\/\/fordcargoparca.com\/","name":"Kamil Y\u0131lmaz Otomotiv - Ford Cargo Par\u00e7a","description":"","publisher":{"@id":"https:\/\/fordcargoparca.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fordcargoparca.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/fordcargoparca.com\/#organization","name":"Kamil Y\u0131lmaz Otomotiv - Ford Cargo Par\u00e7a","url":"https:\/\/fordcargoparca.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/fordcargoparca.com\/#\/schema\/logo\/image\/","url":"https:\/\/fordcargoparca.com\/wp-content\/uploads\/2023\/07\/cropped-kamilyilmazlogo3.png","contentUrl":"https:\/\/fordcargoparca.com\/wp-content\/uploads\/2023\/07\/cropped-kamilyilmazlogo3.png","width":1080,"height":720,"caption":"Kamil Y\u0131lmaz Otomotiv - Ford Cargo Par\u00e7a"},"image":{"@id":"https:\/\/fordcargoparca.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fordtrucksparts\/","https:\/\/www.instagram.com\/kamilyilmazotomotiv\/"]}]}},"_links":{"self":[{"href":"https:\/\/fordcargoparca.com\/en\/wp-json\/wp\/v2\/product\/45428"}],"collection":[{"href":"https:\/\/fordcargoparca.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/fordcargoparca.com\/en\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/fordcargoparca.com\/en\/wp-json\/wp\/v2\/product\/45428\/revisions"}],"wp:attachment":[{"href":"https:\/\/fordcargoparca.com\/en\/wp-json\/wp\/v2\/media?parent=45428"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/fordcargoparca.com\/en\/wp-json\/wp\/v2\/product_cat?post=45428"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/fordcargoparca.com\/en\/wp-json\/wp\/v2\/product_tag?post=45428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}